{"id":6797,"date":"2023-03-08T17:19:01","date_gmt":"2023-03-08T22:19:01","guid":{"rendered":"http:\/\/localhost\/blogchullos\/?p=6797"},"modified":"2023-03-08T17:19:01","modified_gmt":"2023-03-08T22:19:01","slug":"catarata-de-carpishuyacu","status":"publish","type":"post","link":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu","title":{"rendered":"Catarata de Carpishuyacu"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17470 aligncenter\" src=\"http:\/\/localhost\/chullostravelperublog\/wp-content\/uploads\/2023\/03\/Catarata-de-Carpishuyaco.jpg\" alt=\"\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.chullostravelperu.com\/blog\/wp-content\/uploads\/2023\/03\/Catarata-de-Carpishuyaco.jpg 1000w, https:\/\/www.chullostravelperu.com\/blog\/wp-content\/uploads\/2023\/03\/Catarata-de-Carpishuyaco-300x180.jpg 300w, https:\/\/www.chullostravelperu.com\/blog\/wp-content\/uploads\/2023\/03\/Catarata-de-Carpishuyaco-768x461.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/h1>\n<h1 style=\"text-align: center;\">Catarata de Carpishuyacu<\/h1>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #000000;\">\u00bfD\u00f3nde se ubica?<\/span><\/h4>\n<p>Esta catarata se encuentra a 35 kil\u00f3metros de la carretera que nos lleva a la ciudad de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Yurimaguas\">Yurimaguas<\/a>, en la regi\u00f3n San Mart\u00edn espec\u00edficamente en el caser\u00edo San Jos\u00e9<\/p>\n<h4><span style=\"color: #000000;\">\u00bfC\u00f3mo llegar desde Lima?<\/span><\/h4>\n<p>Si queremos llegar a esta hermosa ca\u00edda de agua desde la ciudad de Lima, lo primero que tenemos que hacer es tomar un bus hasta Tarapoto:<\/p>\n<h4><span style=\"color: #000000;\">Empresas de bus:<\/span><\/h4>\n<ul>\n<li>Tepsa<\/li>\n<li>Civa<\/li>\n<li>Mobil Bus<\/li>\n<\/ul>\n<h4><span style=\"color: #000000;\">Camino<\/span><\/h4>\n<p>Cuando lleguemos a Tarapoto debemos de tomar una movilidad hasta \u00abEl caserio San Jos\u00e9\u00bb. Desde este punto comenzamos el recorrido hasta la Catarata de Carpishuyacu en una caminata de 45 minutos aproximadamente.<\/p>\n<p>El recorrido es corto pero presenta algunas dificultades como desniveles en el suelo, se recomienda ir acompa\u00f1ados por un local o persona que ya haya visitado las Cataratas de Carpishuyacu.<\/p>\n<p>De camino tendremos la suerte de atravesar un r\u00edo en un bote o balsa lo cual har\u00e1 de nuestra experiencia algo completamente \u00fanico ya que estaremos rodeados de <a href=\"http:\/\/localhost\/blogchullos\/blog\/lago-sandoval\/\">vegetaci\u00f3n<\/a> y peces los cuales podremos observar en sus limpias aguas, sin duda una de las mejores postales teniendo como protagonista la selva peruana.<\/p>\n<p>Al ver los ba\u00f1os termales de San Jos\u00e9 sabremos que hemos llegado ya que se encuentran en la parte final de dicho camino.<\/p>\n<h4><span style=\"color: #000000;\">Datos<\/span><\/h4>\n<p>La Catarata Pishurayacu le debe su nombre al vocablo Quechua, ya que proviene de dos palabras:<\/p>\n<p>PISHURA: La cual se sabe que se refiera a la parte \u00edntima de la mujer<\/p>\n<p>YACU: La cual significa agua<\/p>\n<p>Este nombre lo tiene porque en la parte m\u00e1s alta y donde nace podemos observar que tiene forma de vagina, de ah\u00ed el nombre que le pusieron los pobladores\u00a0 que viven cerca al caser\u00edo.<\/p>\n<h4><span style=\"color: #000000;\">\u00bfCu\u00e1nto cuesta la entrada?<\/span><\/h4>\n<p>La entrada tiene un m\u00f3dico precio de 5 soles, es un lugar hermoso y econ\u00f3mico para poder visitar.<\/p>\n<p>Presta mucha atenci\u00f3n a tu al rededor ya que podr\u00e1s observar algunos animalitos entre la densa vegetaci\u00f3n, como ya mencionamos la caminata dura alrededor de 45-60 minutos pero lo recomendable es hacerlo a paso lento y tranquilo ya que casi siempre tenemos la presencia de lloviznas y esto hace que el camino hecho de piedras sea un poco resbaloso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Catarata de Carpishuyacu &nbsp; \u00bfD\u00f3nde se ubica? Esta catarata se encuentra a 35 kil\u00f3metros de la carretera que nos lleva a la ciudad de Yurimaguas, en la regi\u00f3n San Mart\u00edn espec\u00edficamente en el caser\u00edo San Jos\u00e9 \u00bfC\u00f3mo llegar desde Lima? Si queremos llegar a esta hermosa ca\u00edda de agua desde la ciudad de Lima, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,51],"tags":[],"class_list":["post-6797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-tarapoto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catarata de Carpishuyacu|Todo lo que debes de saber|<\/title>\n<meta name=\"description\" content=\"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catarata de Carpishuyacu|Todo lo que debes de saber|\" \/>\n<meta property=\"og:description\" content=\"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu\" \/>\n<meta property=\"og:site_name\" content=\"Chullos Travel Peru Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-08T22:19:01+00:00\" \/>\n<meta name=\"author\" content=\"Mr Suicide Sheep\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mr Suicide Sheep\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu\"},\"author\":{\"name\":\"Mr Suicide Sheep\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/#\\\/schema\\\/person\\\/32ea98473caea578cb0113769fa9c6a8\"},\"headline\":\"Catarata de Carpishuyacu\",\"datePublished\":\"2023-03-08T22:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu\"},\"wordCount\":384,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Blog\",\"Tarapoto Blog\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu\",\"url\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu\",\"name\":\"Catarata de Carpishuyacu|Todo lo que debes de saber|\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-03-08T22:19:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/#\\\/schema\\\/person\\\/32ea98473caea578cb0113769fa9c6a8\"},\"description\":\"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/catarata-de-carpishuyacu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catarata de Carpishuyacu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/\",\"name\":\"Chullos Travel Peru Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/#\\\/schema\\\/person\\\/32ea98473caea578cb0113769fa9c6a8\",\"name\":\"Mr Suicide Sheep\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g\",\"caption\":\"Mr Suicide Sheep\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/chullosperublog\"],\"url\":\"https:\\\/\\\/www.chullostravelperu.com\\\/blog\\\/author\\\/mr-suicide-sheep\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catarata de Carpishuyacu|Todo lo que debes de saber|","description":"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu","og_locale":"es_ES","og_type":"article","og_title":"Catarata de Carpishuyacu|Todo lo que debes de saber|","og_description":"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu","og_url":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu","og_site_name":"Chullos Travel Peru Blog","article_published_time":"2023-03-08T22:19:01+00:00","author":"Mr Suicide Sheep","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mr Suicide Sheep","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#article","isPartOf":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu"},"author":{"name":"Mr Suicide Sheep","@id":"https:\/\/www.chullostravelperu.com\/blog\/#\/schema\/person\/32ea98473caea578cb0113769fa9c6a8"},"headline":"Catarata de Carpishuyacu","datePublished":"2023-03-08T22:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu"},"wordCount":384,"commentCount":0,"image":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#primaryimage"},"thumbnailUrl":"","articleSection":["Blog","Tarapoto Blog"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu","url":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu","name":"Catarata de Carpishuyacu|Todo lo que debes de saber|","isPartOf":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#primaryimage"},"image":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#primaryimage"},"thumbnailUrl":"","datePublished":"2023-03-08T22:19:01+00:00","author":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/#\/schema\/person\/32ea98473caea578cb0113769fa9c6a8"},"description":"La catarata se encuentra a 35 Km de la carretera que nos lleva a la ciudad de Yurimaguas, en el caser\u00edo San Jos\u00e9|\u00a0Catarata de Carpishuyacu","breadcrumb":{"@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.chullostravelperu.com\/blog\/catarata-de-carpishuyacu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.chullostravelperu.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Catarata de Carpishuyacu"}]},{"@type":"WebSite","@id":"https:\/\/www.chullostravelperu.com\/blog\/#website","url":"https:\/\/www.chullostravelperu.com\/blog\/","name":"Chullos Travel Peru Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chullostravelperu.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Person","@id":"https:\/\/www.chullostravelperu.com\/blog\/#\/schema\/person\/32ea98473caea578cb0113769fa9c6a8","name":"Mr Suicide Sheep","image":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/secure.gravatar.com\/avatar\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/996c6a8f582dbc42ada5a593327b4a6a3d2f1ff9f13601cd548550f78f300d7b?s=96&d=mm&r=g","caption":"Mr Suicide Sheep"},"sameAs":["http:\/\/localhost\/chullosperublog"],"url":"https:\/\/www.chullostravelperu.com\/blog\/author\/mr-suicide-sheep"}]}},"_links":{"self":[{"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/posts\/6797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/comments?post=6797"}],"version-history":[{"count":0,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/posts\/6797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/media?parent=6797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/categories?post=6797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chullostravelperu.com\/blog\/wp-json\/wp\/v2\/tags?post=6797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}